{"id":3443,"date":"2026-01-13T19:03:40","date_gmt":"2026-01-13T19:03:40","guid":{"rendered":"https:\/\/chrissmart.de\/?p=3443"},"modified":"2026-01-14T15:57:22","modified_gmt":"2026-01-14T15:57:22","slug":"homematic-ip-home-control-unit-starke-zentrale","status":"publish","type":"post","link":"https:\/\/chrissmart.de\/fr\/homematic-ip-home-control-unit-centrale-forte\/","title":{"rendered":"Unit\u00e9 de contr\u00f4le domotique Homematic IP \u2013 une unit\u00e9 centrale puissante ax\u00e9e sur la localisation"},"content":{"rendered":"<p class=\"has-medium-font-size\">Le site <strong>Unit\u00e9 de contr\u00f4le domestique Homematic IP<\/strong> est la centrale la plus performante du portefeuille Homematic-IP et s'adresse aux utilisateurs qui souhaitent que leur Smart Home <strong>fiable, local et ax\u00e9 sur la protection des donn\u00e9es<\/strong> de la maison. Elle associe les fonctions classiques de la maison intelligente \u00e0 une architecture de syst\u00e8me moderne et cr\u00e9e la base d'installations stables \u00e0 long terme - de la maison individuelle aux syst\u00e8mes plus complexes.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Br\u00e8ve pr\u00e9sentation de l'unit\u00e9 de contr\u00f4le \u00e0 domicile Homematic IP<\/h2>\n\n\n\n<p class=\"has-medium-font-size\">La Home Control Unit constitue l'\u00e9l\u00e9ment de commande central pour les composants IP Homematic connect\u00e9s. Elle g\u00e8re tous les appareils connect\u00e9s, ex\u00e9cute les automatismes et les profils temporels et enregistre localement les donn\u00e9es de configuration et de mesure. Contrairement aux solutions purement bas\u00e9es sur le cloud, elle est <strong>ne d\u00e9pend pas d'une connexion Internet permanente<\/strong>.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">L'installation et l'utilisation se font via l'application IP Homematic. En compl\u00e9ment, une interface web locale, appel\u00e9e HCUweb, est disponible pour les r\u00e9glages du syst\u00e8me et du r\u00e9seau. La centrale convient donc aussi bien pour <strong>D\u00e9butant<\/strong> que pour <strong>utilisateurs avanc\u00e9s<\/strong>. La connexion au routeur ou \u00e0 Internet se fait via LAN ou Wlan.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Mode en ligne et contr\u00f4le local<\/h2>\n\n\n\n<p class=\"has-medium-font-size\">L'unit\u00e9 de contr\u00f4le \u00e0 domicile Homematic IP prend en charge deux modes de fonctionnement :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-medium-font-size\"><strong>Mode en ligne :<\/strong> Acc\u00e8s \u00e0 distance optionnel via l'application IP Homematic, par ex. pour la commande \u00e0 distance ou les demandes d'\u00e9tat<\/li>\n\n\n\n<li class=\"has-medium-font-size\"><strong>Op\u00e9ration locale :<\/strong> Les automatismes, les sc\u00e9narios et les commandes d'appareils fonctionnent directement sur la centrale, m\u00eame sans connexion Internet. L'activation se fait via HCUweb. <\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size\">C'est justement l'exploitation locale qui augmente <strong>S\u00e9curit\u00e9 de fonctionnement<\/strong> clairement. M\u00eame en cas de panne d'Internet ou du cloud, les fonctions telles que les automatismes de chauffage, d'\u00e9clairage ou de s\u00e9curit\u00e9 restent actives de mani\u00e8re fiable.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Protection des donn\u00e9es<\/h2>\n\n\n\n<p class=\"has-medium-font-size\">La protection des donn\u00e9es est un \u00e9l\u00e9ment central, l'unit\u00e9 Home Control mise sur <strong>traitement local<\/strong>, <strong>communication crypt\u00e9e<\/strong> et une <strong>connexion au cloud en option<\/strong>, qui peut \u00eatre activ\u00e9e ou d\u00e9sactiv\u00e9e. Les automatismes et les commandes d'appareils sont ex\u00e9cut\u00e9s en mode local directement sur la centrale, de sorte que les donn\u00e9es sensibles ne doivent pas obligatoirement quitter le r\u00e9seau domestique.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">En compl\u00e9ment, il est pertinent que le fabricant <strong>eQ-3<\/strong>, sous la marque de laquelle Homematic IP est d\u00e9velopp\u00e9. <strong>Si\u00e8ge social en Allemagne<\/strong> a \u00e9t\u00e9 mise en place. L'entreprise est ainsi soumise aux <strong>les exigences allemandes et europ\u00e9ennes en mati\u00e8re de protection des donn\u00e9es<\/strong>, Le pr\u00e9sent r\u00e8glement s'inscrit dans le cadre de la l\u00e9gislation europ\u00e9enne sur la protection des donn\u00e9es, en particulier le r\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es (RGPD).<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Compatibilit\u00e9 et extension du syst\u00e8me jusqu'\u00e0 350 appareils<\/strong><\/h2>\n\n\n\n<p class=\"has-medium-font-size\">L'unit\u00e9 Home Control est reli\u00e9e \u00e0 l'ensemble <a href=\"https:\/\/chrissmart.de\/fr\/category\/homematic_ip\/\" data-type=\"link\" data-id=\"https:\/\/chrissmart.de\/category\/homematic_ip\/\">\u00c9cosyst\u00e8me IP Homematic<\/a> compatibles entre elles. Au total, il est possible de <strong>jusqu'\u00e0 350 appareils<\/strong> dans un seul syst\u00e8me. Nous indiquons comme restriction que 120 de ces appareils sont connect\u00e9s par radio. En plus des composants radio, il est possible d'utiliser des points d'acc\u00e8s correspondants. <strong>Appareils filaires<\/strong> \u00eatre int\u00e9gr\u00e9es. <\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Surveillance de l'\u00e9nergie via EEBUS<\/strong><\/h2>\n\n\n\n<p class=\"has-medium-font-size\">Un domaine fonctionnel orient\u00e9 vers l'avenir de l'unit\u00e9 Home Control est le <strong>Surveillance de l'\u00e9nergie via l'interface EEBUS int\u00e9gr\u00e9e<\/strong>. Cela permet aux consommateurs d'\u00e9nergie comme <strong>Pompes \u00e0 chaleur<\/strong>, <strong>Climatiseurs<\/strong> ou <strong>Bo\u00eetes murales<\/strong> et les surveiller.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Actuellement, l'int\u00e9gration EEBUS sert \u00e0 <strong>Saisie et \u00e9valuation des donn\u00e9es de mesure<\/strong>. Selon les indications du fabricant, il est pr\u00e9vu que <strong>dans une future mise \u00e0 jour du logiciel<\/strong> \u00e9galement <strong>Fonctions de contr\u00f4le<\/strong> pour les appareils int\u00e9gr\u00e9s via EEBUS. L'objectif est d'\u00e9tendre la gestion de l'\u00e9nergie dans les maisons intelligentes.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Pr\u00eat pour l'avenir gr\u00e2ce aux plug-ins : extension flexible de la maison intelligente<\/strong><\/h2>\n\n\n\n<p class=\"has-medium-font-size\">Une autre caract\u00e9ristique centrale de l'unit\u00e9 Home Control est le <strong>Syst\u00e8me de plugins<\/strong>. Des plugins sont d\u00e9j\u00e0 disponibles pour <strong>Philips Hue<\/strong> ainsi que pour les <strong>CCU3<\/strong>, Le syst\u00e8me de gestion de l'information de l'entreprise est bas\u00e9 sur un syst\u00e8me de gestion de l'information qui permet d'int\u00e9grer plus facilement les syst\u00e8mes existants.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">De plus, la centrale dispose d'un <strong>mode d\u00e9veloppeur int\u00e9gr\u00e9<\/strong>. Celui-ci permet, <strong>d\u00e9velopper ses propres plugins<\/strong> et de l'ex\u00e9cuter directement sur l'unit\u00e9 Home Control. Les extensions peuvent ainsi \u00eatre exploit\u00e9es localement et adapt\u00e9es individuellement. Selon les indications du fabricant, il est pr\u00e9vu \u00e0 l'avenir <strong>plugins test\u00e9s et certifi\u00e9s <\/strong>\u00e9largir progressivement l'offre.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Conclusion<\/strong><\/h2>\n\n\n\n<p class=\"has-medium-font-size\">Le site <strong>Unit\u00e9 de contr\u00f4le domestique Homematic IP<\/strong> est une centrale Smart-Home performante clairement orient\u00e9e vers <strong>contr\u00f4le local, protection des donn\u00e9es et s\u00e9curit\u00e9 en cas de panne<\/strong>. Avec le soutien de <strong>jusqu'\u00e0 350 appareils<\/strong> (dont <strong>120 par radio<\/strong>), la combinaison flexible de <strong>Fonctionnement en ligne et hors ligne<\/strong>, le <strong>Surveillance de l'\u00e9nergie via EEBUS<\/strong> ainsi que le <strong>Approche par plug-in<\/strong> elle offre une base \u00e0 l'\u00e9preuve du temps pour des syst\u00e8mes smart home con\u00e7us sur le long terme. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">Ceux qui n'ont besoin ni du monitoring \u00e9nerg\u00e9tique ni du fonctionnement local hors ligne peuvent alternativement jeter un coup d'\u0153il sur le <strong>Homematic IP Point d'acc\u00e8s 2<\/strong> de lancer le message. Celui-ci est <strong>nettement moins cher<\/strong>, soutient \u00e9galement <strong>jusqu'\u00e0 120 radios<\/strong> et convient bien aux installations IP Homematic classiques bas\u00e9es sur le cloud.<\/p>\n\n\n\n<p class=\"has-small-font-size\">Source\/photo : (<a href=\"https:\/\/homematic-ip.com\/de\/produkt\/home-control-unit\" data-type=\"link\" data-id=\"https:\/\/homematic-ip.com\/de\/produkt\/home-control-unit\" rel=\"nofollow noopener\" target=\"_blank\">Homematic IP<\/a>\/Amazon \/Image Generator)<\/p>\n\n\n<div class=\"affblk-cta-wrapper  wp-block-affiliatex-cta\" id=\"affiliatex-style-block-27c7570c-eee8-4605-a10a-617df701dc95\">\n\t<div class=\"layout-type-1 left   bg-color\" >\n\t\t<div class=\"content-wrapper\">\n\t\t\t<div class=\"content-wrap\">\n\t\t\t\t<p class=\"affliatex-cta-title\">\n\t\t\t\t\t\ud83d\udcac Quelles sont vos exp\u00e9riences avec l'unit\u00e9 de contr\u00f4le \u00e0 domicile Homematic IP ou d'autres centrales Smart Home ? N'h\u00e9sitez pas \u00e0 partager vos appr\u00e9ciations et vos configurations dans les <a href=\"https:\/\/chrissmart.de\/fr\/homematic-ip-home-control-unit-centrale-forte\/#respond\" data-type=\"link\" data-id=\"https:\/\/chrissmart.de\/homematic-ip-home-control-unit-starke-zentrale\/#respond\">Commentaires<\/a>.\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n\n<div class=\"aligncenter wp-block-affiliatex-product-table\" id=\"affiliatex-pdt-table-style-block-6ecec219-9de9-46f0-bdd9-4924f709c0a1\">\n\t<div class=\"affx-pdt-table-container--free affx-block-admin layout-3\">\n\t\t<div class=\"affx-pdt-table-wrapper\">\n\t\t\t\t\t\t\t<div class=\"affx-pdt-table-single\">\n\t\t\t\t<div class=\"affx-pdt-img-wrapper\">\n\t<img decoding=\"async\" width=\"404\" height=\"450\" src=\"https:\/\/chrissmart.de\/wp-content\/uploads\/2026\/01\/71AhIQoaE8L._AC_SY450_1.jpg\" class=\"attachment-full size-full not-transparent\" alt=\"Unit\u00e9 de contr\u00f4le domestique Homematic IP\" style=\"--dominant-color: #c8cdd0;height: auto\" data-has-transparency=\"false\" data-dominant-color=\"c8cdd0\" \/><\/div>\n\t\t<div class=\"affx-pdt-content-wrap\">\n\t\t<div class=\"affx-content-left\">\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"affx-pdt-name\"><strong>Unit\u00e9 de contr\u00f4le domestique Homematic IP<\/strong><\/h5>\n\t\t\t<div class=\"affx-rating-wrap\"><\/div>\n\t\t\t\t\t\t<div class=\"affx-pdt-desc\">\t<p class=\"affiliatex-content\">Centrale Smart Home, contr\u00f4le num\u00e9rique par application gratuite, Alexa ainsi que Google Assistant, mode en ligne et hors ligne, protection \u00e9lev\u00e9e des donn\u00e9es<\/p>\n<\/div>\n\t\t<\/div>\n\t\t<div class=\"affx-pdt-button-wrap\">\n\t\t\t<div class=\"affx-btn-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"affx-btn-inner\">\n\t<a href=\"https:\/\/amzn.to\/4pyKNEL\" class=\"affiliatex-button secondary\" target=\"_blank\" rel=\"nofollow noopener\">\n\t\t\t\tVoir en magasin*\t\t\t<\/a>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n<div class=\"aligncenter wp-block-affiliatex-product-table\" id=\"affiliatex-pdt-table-style-block-b90e2f26-6209-4d25-8dad-7227b2442487\">\n\t<div class=\"affx-pdt-table-container--free affx-block-admin layout-3\">\n\t\t<div class=\"affx-pdt-table-wrapper\">\n\t\t\t\t\t\t\t<div class=\"affx-pdt-table-single\">\n\t\t\t\t<div class=\"affx-pdt-img-wrapper\">\n\t<img decoding=\"async\" width=\"1419\" height=\"1500\" src=\"https:\/\/chrissmart.de\/wp-content\/uploads\/2026\/01\/510VI9p193L._AC_SL1500_1.jpg\" class=\"attachment-full size-full not-transparent\" alt=\"Homematic IP Centrale Smart Home CCU3\" style=\"--dominant-color: #e9e9eb;height: auto\" data-has-transparency=\"false\" data-dominant-color=\"e9e9eb\" \/><\/div>\n\t\t<div class=\"affx-pdt-content-wrap\">\n\t\t<div class=\"affx-content-left\">\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"affx-pdt-name\"><strong>Homematic IP Centrale Smart Home CCU3<\/strong><\/h5>\n\t\t\t<div class=\"affx-rating-wrap\"><\/div>\n\t\t\t\t\t\t<div class=\"affx-pdt-desc\">\t<p class=\"affiliatex-content\">La centrale performante pour les professionnels de la maison intelligente pour un contr\u00f4le local et confortable de la maison intelligente.<\/p>\n<\/div>\n\t\t<\/div>\n\t\t<div class=\"affx-pdt-button-wrap\">\n\t\t\t<div class=\"affx-btn-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"affx-btn-inner\">\n\t<a href=\"https:\/\/amzn.to\/45dA63o\" class=\"affiliatex-button secondary\" target=\"_blank\" rel=\"nofollow noopener\">\n\t\t\t\tVoir en magasin*\t\t\t<\/a>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n<div class=\"aligncenter wp-block-affiliatex-product-table\" id=\"affiliatex-pdt-table-style-block-8d6f5979-581e-45b4-bb21-e56cdef023ef\">\n\t<div class=\"affx-pdt-table-container--free affx-block-admin layout-3\">\n\t\t<div class=\"affx-pdt-table-wrapper\">\n\t\t\t\t\t\t\t<div class=\"affx-pdt-table-single\">\n\t\t\t\t<div class=\"affx-pdt-img-wrapper\">\n\t<img decoding=\"async\" width=\"1500\" height=\"1340\" src=\"https:\/\/chrissmart.de\/wp-content\/uploads\/2026\/01\/71NRl4yebbL._AC_SL1500_1.jpg\" class=\"attachment-full size-full not-transparent\" alt=\"Homematic IP Point d&#039;acc\u00e8s 2\" style=\"--dominant-color: #e1e6e7;height: auto\" data-has-transparency=\"false\" data-dominant-color=\"e1e6e7\" \/><\/div>\n\t\t<div class=\"affx-pdt-content-wrap\">\n\t\t<div class=\"affx-content-left\">\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"affx-pdt-name\"><strong>Homematic IP Point d'acc\u00e8s 2<\/strong><\/h5>\n\t\t\t<div class=\"affx-rating-wrap\"><\/div>\n\t\t\t\t\t\t<div class=\"affx-pdt-desc\">\t<p class=\"affiliatex-content\">Passerelle pour maison intelligente avec application gratuite et commande vocale via Amazon Alexa<\/p>\n<\/div>\n\t\t<\/div>\n\t\t<div class=\"affx-pdt-button-wrap\">\n\t\t\t<div class=\"affx-btn-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"affx-btn-inner\">\n\t<a href=\"https:\/\/amzn.to\/4pB5YWQ\" class=\"affiliatex-button secondary\" target=\"_blank\" rel=\"nofollow noopener\">\n\t\t\t\tVoir en magasin*\t\t\t<\/a>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Die Homematic IP Home Control Unit ist die leistungsf\u00e4higste Zentrale im Homematic-IP-Portfolio und richtet sich an Nutzer, die ihr Smart Home zuverl\u00e4ssig, lokal und datenschutzorientiert betreiben m\u00f6chten. Sie verbindet klassische Smart-Home-Funktionen mit moderner Systemarchitektur und schafft die Grundlage f\u00fcr langfristig stabile Installationen \u2013 vom Einfamilienhaus bis zu komplexeren Systeme. Kurze Vorstellung der Homematic IP Home [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3456,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"googlesitekit_rrm_CAowl7q2DA:productID":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-3443","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-homematic_ip"],"acf":[],"jetpack_featured_media_url":"https:\/\/chrissmart.de\/wp-content\/uploads\/2026\/01\/Homematic-IP-Home-Control-Unit-\u2013-leistungsstarke-Zentrale-mit-lokalem-Fokus.png","blog_post_layout_featured_media_urls":{"thumbnail":["https:\/\/chrissmart.de\/wp-content\/uploads\/2026\/01\/Homematic-IP-Home-Control-Unit-\u2013-leistungsstarke-Zentrale-mit-lokalem-Fokus-150x150.png",150,150,true],"full":["https:\/\/chrissmart.de\/wp-content\/uploads\/2026\/01\/Homematic-IP-Home-Control-Unit-\u2013-leistungsstarke-Zentrale-mit-lokalem-Fokus.png",1200,733,false]},"categories_names":{"5":{"name":"Homematic IP","link":"https:\/\/chrissmart.de\/fr\/category\/homematic_ip\/"}},"tags_names":[],"comments_number":"0","wpmagazine_modules_lite_featured_media_urls":{"thumbnail":["https:\/\/chrissmart.de\/wp-content\/uploads\/2026\/01\/Homematic-IP-Home-Control-Unit-\u2013-leistungsstarke-Zentrale-mit-lokalem-Fokus-150x150.png",150,150,true],"cvmm-medium":["https:\/\/chrissmart.de\/wp-content\/uploads\/2026\/01\/Homematic-IP-Home-Control-Unit-\u2013-leistungsstarke-Zentrale-mit-lokalem-Fokus-300x300.png",300,300,true],"cvmm-medium-plus":["https:\/\/chrissmart.de\/wp-content\/uploads\/2026\/01\/Homematic-IP-Home-Control-Unit-\u2013-leistungsstarke-Zentrale-mit-lokalem-Fokus-305x207.png",305,207,true],"cvmm-portrait":["https:\/\/chrissmart.de\/wp-content\/uploads\/2026\/01\/Homematic-IP-Home-Control-Unit-\u2013-leistungsstarke-Zentrale-mit-lokalem-Fokus-400x600.png",400,600,true],"cvmm-medium-square":["https:\/\/chrissmart.de\/wp-content\/uploads\/2026\/01\/Homematic-IP-Home-Control-Unit-\u2013-leistungsstarke-Zentrale-mit-lokalem-Fokus-600x600.png",600,600,true],"cvmm-large":["https:\/\/chrissmart.de\/wp-content\/uploads\/2026\/01\/Homematic-IP-Home-Control-Unit-\u2013-leistungsstarke-Zentrale-mit-lokalem-Fokus-1024x1024.png",1024,1024,true],"cvmm-small":["https:\/\/chrissmart.de\/wp-content\/uploads\/2026\/01\/Homematic-IP-Home-Control-Unit-\u2013-leistungsstarke-Zentrale-mit-lokalem-Fokus-130x95.png",130,95,true],"full":["https:\/\/chrissmart.de\/wp-content\/uploads\/2026\/01\/Homematic-IP-Home-Control-Unit-\u2013-leistungsstarke-Zentrale-mit-lokalem-Fokus.png",1200,733,false]},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/chrissmart.de\/fr\/wp-json\/wp\/v2\/posts\/3443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chrissmart.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chrissmart.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chrissmart.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chrissmart.de\/fr\/wp-json\/wp\/v2\/comments?post=3443"}],"version-history":[{"count":0,"href":"https:\/\/chrissmart.de\/fr\/wp-json\/wp\/v2\/posts\/3443\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chrissmart.de\/fr\/wp-json\/wp\/v2\/media\/3456"}],"wp:attachment":[{"href":"https:\/\/chrissmart.de\/fr\/wp-json\/wp\/v2\/media?parent=3443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chrissmart.de\/fr\/wp-json\/wp\/v2\/categories?post=3443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chrissmart.de\/fr\/wp-json\/wp\/v2\/tags?post=3443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}